{"id":11883,"date":"2017-02-16T17:05:49","date_gmt":"2017-02-16T19:05:49","guid":{"rendered":"https:\/\/pt.blogs.cam4.com\/files\/2017\/02\/sexxesnow2.jpg"},"modified":"2017-02-16T17:05:49","modified_gmt":"2017-02-16T19:05:49","slug":"sexxesnow2","status":"inherit","type":"attachment","link":"https:\/\/pt.cam4.com\/blog\/confira-as-fotos-mais-quentes-do-sexy-valentine-cam4-2017\/sexxesnow2\/","title":{"rendered":"sexxesnow2"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/02\/sexxesnow2.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"sexxesnow2 - Cam4 Brasil e Portugal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/02\/sexxesnow2.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Cam4 Brasil e Portugal\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/02\/sexxesnow2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"Admin\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pt.cam4.com\/blog\/#website\",\"url\":\"https:\/\/pt.cam4.com\/blog\/\",\"name\":\"Cam4 Brasil e Portugal\",\"description\":\"Entrevistas com performers do Cam4 e novidades sobre o site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/pt.cam4.com\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/02\/sexxesnow2.jpg#webpage\",\"url\":\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/02\/sexxesnow2.jpg\",\"name\":\"sexxesnow2 - Cam4 Brasil e Portugal\",\"isPartOf\":{\"@id\":\"https:\/\/pt.cam4.com\/blog\/#website\"},\"datePublished\":\"2017-02-16T19:05:49+00:00\",\"dateModified\":\"2017-02-16T19:05:49+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/02\/sexxesnow2.jpg\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/02\/sexxesnow2.jpg'><img width=\"300\" height=\"169\" src=\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/02\/sexxesnow2-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/02\/sexxesnow2-300x169.jpg 300w, https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/02\/sexxesnow2-1024x576.jpg 1024w, https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/02\/sexxesnow2-600x338.jpg 600w, https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/02\/sexxesnow2.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p class=\"attachment\"><a href='https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/02\/sexxesnow2.jpg'><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":675,"file":"2017\/02\/sexxesnow2.jpg","sizes":{"thumbnail":{"file":"sexxesnow2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/02\/sexxesnow2-150x150.jpg"},"medium":{"file":"sexxesnow2-300x169.jpg","width":300,"height":169,"mime_type":"image\/jpeg","source_url":"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/02\/sexxesnow2-300x169.jpg"},"large":{"file":"sexxesnow2-1024x576.jpg","width":1024,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/02\/sexxesnow2-1024x576.jpg"},"wysija-newsletters-max":{"file":"sexxesnow2-600x338.jpg","width":600,"height":338,"mime_type":"image\/jpeg","source_url":"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/02\/sexxesnow2-600x338.jpg"},"full":{"file":"sexxesnow2.jpg","width":1200,"height":675,"mime_type":"image\/jpeg","source_url":"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/02\/sexxesnow2.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":11834,"source_url":"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/02\/sexxesnow2.jpg","_links":{"self":[{"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/media\/11883"}],"collection":[{"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/comments?post=11883"}]}}