{"id":12046,"date":"2017-03-02T16:52:10","date_gmt":"2017-03-02T19:52:10","guid":{"rendered":"https:\/\/pt.blogs.cam4.com\/files\/2017\/03\/fabilinda1_6.jpg"},"modified":"2017-03-02T16:52:10","modified_gmt":"2017-03-02T19:52:10","slug":"fabilinda1_6-2","status":"inherit","type":"attachment","link":"https:\/\/pt.cam4.com\/blog\/ganhadores-melhores-fotos-de-carnaval-cam4-e-loja-do-prazer\/fabilinda1_6-2\/","title":{"rendered":"fabilinda1_6"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/03\/fabilinda1_6.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"fabilinda1_6 - Cam4 Brasil e Portugal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/03\/fabilinda1_6.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Cam4 Brasil e Portugal\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/03\/fabilinda1_6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"320\" \/>\n\t<meta property=\"og:image:height\" content=\"176\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"Admin\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pt.cam4.com\/blog\/#website\",\"url\":\"https:\/\/pt.cam4.com\/blog\/\",\"name\":\"Cam4 Brasil e Portugal\",\"description\":\"Entrevistas com performers do Cam4 e novidades sobre o site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/pt.cam4.com\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/03\/fabilinda1_6.jpg#webpage\",\"url\":\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/03\/fabilinda1_6.jpg\",\"name\":\"fabilinda1_6 - Cam4 Brasil e Portugal\",\"isPartOf\":{\"@id\":\"https:\/\/pt.cam4.com\/blog\/#website\"},\"datePublished\":\"2017-03-02T19:52:10+00:00\",\"dateModified\":\"2017-03-02T19:52:10+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/03\/fabilinda1_6.jpg\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/03\/fabilinda1_6.jpg'><img width=\"300\" height=\"165\" src=\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/03\/fabilinda1_6-300x165.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/03\/fabilinda1_6-300x165.jpg 300w, https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/03\/fabilinda1_6.jpg 320w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p class=\"attachment\"><a href='https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/03\/fabilinda1_6.jpg'><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":320,"height":176,"file":"2017\/03\/fabilinda1_6.jpg","sizes":{"thumbnail":{"file":"fabilinda1_6-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/03\/fabilinda1_6-150x150.jpg"},"medium":{"file":"fabilinda1_6-300x165.jpg","width":300,"height":165,"mime_type":"image\/jpeg","source_url":"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/03\/fabilinda1_6-300x165.jpg"},"full":{"file":"fabilinda1_6.jpg","width":320,"height":176,"mime_type":"image\/jpeg","source_url":"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/03\/fabilinda1_6.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":12032,"source_url":"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2017\/03\/fabilinda1_6.jpg","_links":{"self":[{"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/media\/12046"}],"collection":[{"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/comments?post=12046"}]}}