{"id":7417,"date":"2014-12-02T11:48:44","date_gmt":"2014-12-02T13:48:44","guid":{"rendered":"https:\/\/pt.blogs.cam4.com\/files\/2014\/12\/spanishstar.jpg"},"modified":"2014-12-02T11:48:44","modified_gmt":"2014-12-02T13:48:44","slug":"spanishstar-3","status":"inherit","type":"attachment","link":"https:\/\/pt.cam4.com\/blog\/nos-amamos-vermelho-veja-fotos-cam4red\/spanishstar-3\/","title":{"rendered":"spanishstar"},"author":13,"comment_status":"open","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2014\/12\/spanishstar.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"spanishstar - Cam4 Brasil e Portugal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2014\/12\/spanishstar.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Cam4 Brasil e Portugal\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2014\/12\/spanishstar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"906\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pt.cam4.com\/blog\/#website\",\"url\":\"https:\/\/pt.cam4.com\/blog\/\",\"name\":\"Cam4 Brasil e Portugal\",\"description\":\"Entrevistas com performers do Cam4 e novidades sobre o site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/pt.cam4.com\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2014\/12\/spanishstar.jpg#webpage\",\"url\":\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2014\/12\/spanishstar.jpg\",\"name\":\"spanishstar - Cam4 Brasil e Portugal\",\"isPartOf\":{\"@id\":\"https:\/\/pt.cam4.com\/blog\/#website\"},\"datePublished\":\"2014-12-02T13:48:44+00:00\",\"dateModified\":\"2014-12-02T13:48:44+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2014\/12\/spanishstar.jpg\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2014\/12\/spanishstar.jpg'><img width=\"198\" height=\"300\" src=\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2014\/12\/spanishstar-198x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2014\/12\/spanishstar-198x300.jpg 198w, https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2014\/12\/spanishstar.jpg 600w\" sizes=\"(max-width: 198px) 100vw, 198px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p class=\"attachment\"><a href='https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2014\/12\/spanishstar.jpg'><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":600,"height":906,"file":"2014\/12\/spanishstar.jpg","sizes":{"thumbnail":{"file":"spanishstar-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2014\/12\/spanishstar-150x150.jpg"},"medium":{"file":"spanishstar-198x300.jpg","width":198,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2014\/12\/spanishstar-198x300.jpg"},"full":{"file":"spanishstar.jpg","width":600,"height":906,"mime_type":"image\/jpeg","source_url":"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2014\/12\/spanishstar.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":7339,"source_url":"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2014\/12\/spanishstar.jpg","_links":{"self":[{"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/media\/7417"}],"collection":[{"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/comments?post=7417"}]}}