{"id":1019,"date":"2012-04-26T18:45:40","date_gmt":"2012-04-26T21:45:40","guid":{"rendered":"https:\/\/pt.blogs.cam4.com\/?p=1019"},"modified":"2013-07-05T17:25:49","modified_gmt":"2013-07-05T20:25:49","slug":"tv-exibe-acidentalmente-filme-porno-gay-no-noticiario-matinal","status":"publish","type":"post","link":"https:\/\/pt.cam4.com\/blog\/tv-exibe-acidentalmente-filme-porno-gay-no-noticiario-matinal\/","title":{"rendered":"TV exibe acidentalmente filme porn\u00f4 gay no notici\u00e1rio matinal"},"content":{"rendered":"<p><a href=\"https:\/\/pt.cam4.com\/blog\/files\/2012\/04\/afterhours.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-1020\" src=\"https:\/\/pt.cam4.com\/blog\/files\/2012\/04\/afterhours.jpg\" alt=\"\" width=\"550\" height=\"264\" srcset=\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2012\/04\/afterhours.jpg 550w, https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2012\/04\/afterhours-300x144.jpg 300w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/a><\/p>\n<p>O notici\u00e1rio matinal da TV CHCH, do Canad\u00e1, foi interrompido por tr\u00eas minutos com a exibi\u00e7\u00e3o do filme porn\u00f4 gay \u201cAfter hours\u201d, estrelado por Harry Louis, namorado brasileiro do estilista americano<\/p>\n<p>Segundo Mike Katrycz, diretor de jornalismo do canal, a culpa \u00e9 da operadora Shaw Cable, que distribui o sinal da CHCH. Imagina a cara dos espectadores ao ver Harry Louis em a\u00e7\u00e3o em pleno hor\u00e1rio do caf\u00e9 da manh\u00e3?!<\/p>\n<p>&nbsp;<br \/>\nhttps:\/\/www.youtube.com\/watch?v=62vNERgiMcA&#038;feature=player_embedded<\/p>\n","protected":false},"excerpt":{"rendered":"<p><a href=\"https:\/\/pt.cam4.com\/blog\/files\/2012\/04\/afterhours.jpg\"><\/a><\/p>\n<p>O notici\u00e1rio matinal da TV CHCH, do Canad\u00e1, foi interrompido por tr\u00eas minutos com a exibi\u00e7\u00e3o do filme porn\u00f4 gay \u201cAfter<\/p>\n","protected":false},"author":13,"featured_media":1021,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[34413],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pt.cam4.com\/blog\/tv-exibe-acidentalmente-filme-porno-gay-no-noticiario-matinal\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TV exibe acidentalmente filme porn\u00f4 gay no notici\u00e1rio matinal - Cam4 Brasil e Portugal\" \/>\n<meta property=\"og:description\" content=\"O notici\u00e1rio matinal da TV CHCH, do Canad\u00e1, foi interrompido por tr\u00eas minutos com a exibi\u00e7\u00e3o do filme porn\u00f4 gay \u201cAfter\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pt.cam4.com\/blog\/tv-exibe-acidentalmente-filme-porno-gay-no-noticiario-matinal\/\" \/>\n<meta property=\"og:site_name\" content=\"Cam4 Brasil e Portugal\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-26T21:45:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-07-05T20:25:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2012\/04\/afterhours1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"264\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"\">\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data2\" content=\"0 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pt.cam4.com\/blog\/#website\",\"url\":\"https:\/\/pt.cam4.com\/blog\/\",\"name\":\"Cam4 Brasil e Portugal\",\"description\":\"Entrevistas com performers do Cam4 e novidades sobre o site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/pt.cam4.com\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/pt.cam4.com\/blog\/tv-exibe-acidentalmente-filme-porno-gay-no-noticiario-matinal\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/pt.cam4.com\/blog\/wp-content\/blogs.dir\/10\/files\/2012\/04\/afterhours1.jpg\",\"width\":\"550\",\"height\":\"264\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pt.cam4.com\/blog\/tv-exibe-acidentalmente-filme-porno-gay-no-noticiario-matinal\/#webpage\",\"url\":\"https:\/\/pt.cam4.com\/blog\/tv-exibe-acidentalmente-filme-porno-gay-no-noticiario-matinal\/\",\"name\":\"TV exibe acidentalmente filme porn\\u00f4 gay no notici\\u00e1rio matinal - Cam4 Brasil e Portugal\",\"isPartOf\":{\"@id\":\"https:\/\/pt.cam4.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pt.cam4.com\/blog\/tv-exibe-acidentalmente-filme-porno-gay-no-noticiario-matinal\/#primaryimage\"},\"datePublished\":\"2012-04-26T21:45:40+00:00\",\"dateModified\":\"2013-07-05T20:25:49+00:00\",\"author\":{\"@id\":\"\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pt.cam4.com\/blog\/tv-exibe-acidentalmente-filme-porno-gay-no-noticiario-matinal\/\"]}]},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/posts\/1019"}],"collection":[{"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/comments?post=1019"}],"version-history":[{"count":0,"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/posts\/1019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/media\/1021"}],"wp:attachment":[{"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/media?parent=1019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/categories?post=1019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pt.cam4.com\/blog\/wp-json\/wp\/v2\/tags?post=1019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}